{"id":55,"date":"2020-11-09T08:35:14","date_gmt":"2020-11-09T07:35:14","guid":{"rendered":"https:\/\/unterirdis.ch\/wordpress\/?p=55"},"modified":"2022-07-26T18:25:44","modified_gmt":"2022-07-26T16:25:44","slug":"da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt","status":"publish","type":"post","link":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/","title":{"rendered":"Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"55\" class=\"elementor elementor-55\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f53915 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f53915\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0e8f84\" data-id=\"c0e8f84\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8897e39 elementor-widget elementor-widget-spacer\" data-id=\"8897e39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6253a9e elementor-widget elementor-widget-text-editor\" data-id=\"6253a9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>In den \u00f6sterreichischen Ostalpen gibt es gro\u00dfe Salzvorkommen. Diese werden bis heute in Hallstatt und Hallein abgebaut. Beide Orte sind f\u00fcr die Arch\u00e4ologie von gro\u00dfer Bedeutung, denn sie geben einen Einblick in die Lebenswelt der Bronzezeit.\u00a0<\/em><em>Heute gibt es au\u00dfergew\u00f6hnliche Einblicke in die Welt dort: Ich unterhalte mich mit Prof. Dr. Thomas St\u00f6llner \u00fcber seine Arbeit. Wir befinden uns untertage im D\u00fcrrnberg, Hallein. Genauer gesagt in einem Laugwerk. Dort wird Salz mit Wasser aus dem Fels gezogen. Als ich ankomme, stehen Thomas St\u00f6llner und drei seiner Mitarbeiter:innen vor einer Abbauwand und versuchen, mit nachgebauten Pickeln und Keilhauen Salz aus der Wand zu schlagen. Das ist Teil eines Experimentes, das eisenzeitliche Abbaumethoden untersucht. Die untert\u00e4gige Halle, in der wir stehen, ist dunkel, nur das Experiment ist erleuchtet, um die Szene filmen zu k\u00f6nnen.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a523341 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a523341\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-325f503\" data-id=\"325f503\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d7e11e elementor-widget elementor-widget-text-editor\" data-id=\"5d7e11e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Herr St\u00f6llner, Sie sind Montanarch\u00e4ologe. Was bedeutet das?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-87b3d22\" data-id=\"87b3d22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-299f524 elementor-widget elementor-widget-text-editor\" data-id=\"299f524\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Montanarch\u00e4ologie kommt aus dem Lateinischen und hei\u00dft eigentlich \u201eres montanorum\u201c \u2013 alles was mit den Bergwesen zu tun hat. Das ist seit dem 16. Jahrhundert ein Sinnbild f\u00fcr alles aus dem Bergbau. Die Arch\u00e4ologie hat dieses Themenfeld schon im 19. Jahrhundert entdeckt und dann in den 1960er Jahren den Begriff \u201eMontanarch\u00e4ologie\u201c gepr\u00e4gt. Wir verstehen darunter nicht nur das Bergwerk, weil das Bergwerk an sich der Abbau des Rohstoffes ist, sondern alles, was damit zusammenh\u00e4ngt, also auch\u00a0 die Gesellschaft, die Siedlungen und die Wirtschaft. All dies ist mit einem Bergwerk verbunden. Ein sehr, sag ich mal, ganzheitlicher Ansatz, weil man eigentlich alle Aspekte einer Gesellschaft detailliert kennen muss, um ein Bergwerk zu verstehen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06a813f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06a813f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b271e0c\" data-id=\"b271e0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67ffada elementor-widget elementor-widget-text-editor\" data-id=\"67ffada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Das ist sehr spannend. Sie haben mir berichtet, dass Sie das erste Mal als kleiner Junge im Berg waren. Wie war das denn f\u00fcr Sie?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-2471bde\" data-id=\"2471bde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c44ba5 elementor-widget elementor-widget-text-editor\" data-id=\"6c44ba5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich bin in Hallein zur Schule gegangen und wir haben eine Exkursion hier in das Salzbergwerk gemacht. Ich war vielleicht 9 oder 10 Jahre alt. Wir sind hier in die Grube eingefahren. Am meisten haben mich diese engen Baue fasziniert. Im Halleiner Salzbergwerk gibt es einen Grubenbau, den sogenannten \u201e100-j\u00e4hrige Stollen\u201c. Das hat mich fasziniert, weil ich mir gedacht habe: \u201eDa muss man weiter und heraus finden, wohin der Stollen f\u00fchrt.\u201c<\/p><p>Es ist interessant, wenn man in der R\u00fcckschau sieht, was man als Kind schon spannend gefunden hat: H\u00f6hlen, untertage, Grubenbaue, die Arbeit untertage, diese besondere Atmosph\u00e4re. Das hat mich beruflich verfolgt und macht immer noch Spa\u00df.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34f4efa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34f4efa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39088a6\" data-id=\"39088a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8483156 elementor-widget elementor-widget-image\" data-id=\"8483156\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-300x225.jpg\" class=\"attachment-medium size-medium wp-image-52\" alt=\"100j\u00e4hriger Stollen\" srcset=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-300x225.jpg 300w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-1024x768.jpg 1024w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-768x576.jpg 768w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-1536x1152.jpg 1536w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-2048x1536.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6eee829 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6eee829\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-41d9b4c\" data-id=\"41d9b4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70c06cb elementor-widget elementor-widget-text-editor\" data-id=\"70c06cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Wir alle kennen Salz aus unserem Alltag. Aber was ist denn das Besondere an der Arch\u00e4ologie im Salz? Gibt es besondere Herausforderungen? Wie unterscheidet sich das von anderen arch\u00e4ologischen Fachrichtungen?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-8c10577\" data-id=\"8c10577\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb0a762 elementor-widget elementor-widget-text-editor\" data-id=\"eb0a762\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn ich vom Rohstoff herdenke, kann ich sagen, Salz ist ein ganz besonderer Rohstoff, weil man ihn isst und weil er lebenswichtig ist. Deshalb ist er in allen Gesellschaften weltweit ein notwendiges Requisit. Jede Gesellschaft braucht Salz. Das hei\u00dft, wir haben immer eine Art der Salzgewinnung. Das ist das Spannende an der arch\u00e4ologischen Forschung im Salz \u2013 weltweit finden sich \u00e4hnliche Ph\u00e4nomene. Dies gilt auch f\u00fcr schriftlose oder schriftarme Zeiten, die wir in der Arch\u00e4ologie erforschen.<\/p><p>Spannend ist auch, dass Salz ein unglaublich gutes Konservierungsmittel ist. Gerade die arch\u00e4ologischen Funde in Salzbergwerken sind alle so erhalten, wie wenn Sie sie gestern weggeworfen h\u00e4tten. Wir finden also eine unheimliche Breite einer Alltagskultur, die wir anderswo nicht finden. Bei einer normalen Grabung haben Sie Keramik und Metalle, aber nur ganz wenig Organik. Wenn Sie im Salz graben, haben Sie 5% Nichtorganik, alles andere ist Organik. Das hei\u00dft, Sie haben ein komplettes Panoptikum, also eine Gesamtschau, einer alten Gesellschaft, mit alldem was diese Gesellschaft ausmacht \u2013 bis zum Essen. Denn auch f\u00fcr die Herstellung und Konservierung von z.B. Speck oder K\u00e4se war \u2013 und ist bis heute \u2013 Salz notwendig.\u00a0 Oder nehmen wir die Viehwirtschaft: Damit die Tiere Milch f\u00fcr den K\u00e4se geben und eine gute Fleischleitung haben, braucht es auch Salz. Salz ist also wesentlich f\u00fcr eine Gesellschaft.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44b1131 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44b1131\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fd2be53\" data-id=\"fd2be53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2009253 elementor-widget elementor-widget-text-editor\" data-id=\"2009253\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Also ein aktueller Lebensweltbezug f\u00fcr unsere Leser:innen, der sich hier herstellen l\u00e4sst. Sie haben gerade erw\u00e4hnt, Sie arbeiten weltweit. Wo graben Sie denn aktuell?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-6919276\" data-id=\"6919276\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7783767 elementor-widget elementor-widget-text-editor\" data-id=\"7783767\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aktuell graben wir an einem zweiten Salzbergwerk. Das ist ein gro\u00dfes Projekt in Iran, das sich um ein Bergwerk nahe Zanjan dreht. Zanjan ist eine Provinzhauptstadt im Nordwesten Irans. Das Bergwerk ist genauso alt wie der D\u00fcrrnberg bei Hallein, wo ich meine ersten Grabungen gemacht habe. Es ist aus der sogenannten ach\u00e4menidischen Zeit, das ist die Zeit der persischen Gro\u00dfk\u00f6nige, und dort wurde Salz abgebaut. Besonders faszinierend sind die Funde von verungl\u00fcckten Bergleuten. Diese sind um etwa 400 vor unserer Zeitrechnung zu Tode gekommen. Wir haben \u00e4hnliche Funde aus den \u00f6sterreichischen Alpen. Nat\u00fcrlich h\u00e4tte mich immer interessiert, selbst einen solchen Fund zu machen. Aber bis jetzt haben weder wir noch die Kollegen in Hallstatt das geschafft, daf\u00fcr aber unser Kollege Herr Dr. Abolfazl Aali in Iran. Seit vielen Jahren untersuchen wir gemeinsam die \u201eSalzm\u00e4nner\u201c, das Bergwerk und die Umgebung. Das ist ein sch\u00f6nes Projekt und ein unglaublich faszinierender Fundplatz nat\u00fcrlich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6fc172a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6fc172a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8af6155\" data-id=\"8af6155\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edce281 elementor-widget elementor-widget-text-editor\" data-id=\"edce281\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: bolder; color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: 1rem;\">Diese Funde liegen in Museen in Zanjan und in Teheran. Sie haben diese bestimmt auch mal besucht. Wann waren Sie denn das erste Mal dort?<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-f206412\" data-id=\"f206412\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51fce49 elementor-widget elementor-widget-text-editor\" data-id=\"51fce49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich kann mich erinnern, dass ich das erste Mal 2005 w\u00e4hrend einer Exkursion dort war. Wir hatten eine Grabung in Veshnaveh. Ich wusste schon, dass die Funde aus dem Salzbergwerk in Teheran ausgestellt waren, weil mich ein \u00f6sterreichischer Botschafter darauf angesprochen hatte. Er sagte: \u201eDa gibt\u2019s etwas Interessantes, Herr St\u00f6llner.\u201c Ich wusste, dass diese Funde etwas Besonderes sind. Mehrere Jahre habe ich mich darum bem\u00fcht, Kontakte in Iran aufzubauen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-882aa84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"882aa84\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-858599e\" data-id=\"858599e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e80026 elementor-widget elementor-widget-text-editor\" data-id=\"3e80026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Und wie war es, die Salzm\u00e4nner zum ersten Mal zu sehen?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-9d27084\" data-id=\"9d27084\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae5ab61 elementor-widget elementor-widget-text-editor\" data-id=\"ae5ab61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>2005 war der sogenannte \u201eSalzmann 4\u201c zum ersten Mal zu sehen. Er ist durch das Salz gut erhalten und war gerade gefunden worden. Er lag das erste Mal in einer Vitrine und man konnte ihn vor Ort sehen. Das war nat\u00fcrlich unglaublich faszinierend. Wir haben uns immer gefragt, wie wohl ein durch Salz mumifizierter Mensch aussieht. Es gab die alten Berichte aus dem 16. und 17. Jahrhundert, aber eben keine Funde. Alles was jetzt kam, die ganze Forschung um den Mann im Salz im Iran, hat nat\u00fcrlich eine F\u00fclle an Informationen gebracht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c069908 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c069908\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e212e01\" data-id=\"e212e01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccf5fbd elementor-widget elementor-widget-text-editor\" data-id=\"ccf5fbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Zum Beispiel?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-88836d4\" data-id=\"88836d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-005a808 elementor-widget elementor-widget-text-editor\" data-id=\"005a808\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Faszinierendste ist, dass zum Beispiel die ach\u00e4menidischen Bergleute meistens Fremdarbeiter waren und an den Salzberg zum Arbeiten kamen. Und der junge Mann \u2013 \u201eSalzmann 4\u201c \u2013 der ist wirklich faszinierend. Er kam wahrscheinlich erst kurz vor seinem Tod dorthin, wahrscheinlich im Rahmen eines Arbeitsdienstes oder -auftrages. Er war dort wahrscheinlich nur wenige, vielleicht nur ein oder zwei Tage, und ist dann verungl\u00fcckt. Das ist eine sehr dramatische Lebensgeschichte, die man da f\u00fcr einen Sechzehnj\u00e4hrigen ableiten kann. Aber es gibt eine F\u00fclle weiterer Detailinformationen: Wie war er angezogen? Wie war er ausgestattet? Welche Krankheiten hatte er? \u201eSalzmann 4\u201c hatte eine erbliche Krankheit, die man auch an den Knochen sehen kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1eb6a94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1eb6a94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1657c36\" data-id=\"1657c36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69284cc elementor-widget elementor-widget-text-editor\" data-id=\"69284cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Die kommende Sonderausstellung \u201eTod im Salz. Eine Ermittlung in Persien\u201c im Deutschen Bergbau-Museum Bochum dreht sich ja auch um Salzmann 4. Dazu haben sie intensiv mit den Museen in Iran zusammengearbeitet. Jetzt stellt sich die Frage, was ist Besonders an dieser Kooperation?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-8d0a25e\" data-id=\"8d0a25e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2da86d9 elementor-widget elementor-widget-text-editor\" data-id=\"2da86d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich glaube, dass wir Menschen gut daran tun, zusammen zu arbeiten \u2013 auch in Zeiten des Klimawandels und der Coronakrise. Und es bringt uns nichts in dieser Welt, wenn Menschen und Gesellschaften und Staaten gegeneinander arbeiten. Deshalb ist es, glaube ich, aus kulturpolitischer Sicht wichtig, mit Iran zu arbeiten und auf der wissenschaftlichen Arbeitsebene Kontakte zu haben, diese auszubauen und gerade auch zu zeigen, dass trotz aller politischen Differenzen ein Zusammenarbeiten und ein Zusammengehen m\u00f6glich ist. Ich glaube, das ist das Wesentliche bei so einer Ausstellung: Dass man neben den Inhalten auch eine spannende Geschichte erz\u00e4hlt und unsere Forschung zeigt. \u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf20925 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf20925\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96ec5a6\" data-id=\"96ec5a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cccc658 elementor-widget elementor-widget-image\" data-id=\"cccc658\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/Plakatraster_Sonderausstellungen_22_1_-212x300.jpg\" class=\"attachment-medium size-medium wp-image-53\" alt=\"\" srcset=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/Plakatraster_Sonderausstellungen_22_1_-212x300.jpg 212w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/Plakatraster_Sonderausstellungen_22_1_-723x1024.jpg 723w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/Plakatraster_Sonderausstellungen_22_1_-768x1087.jpg 768w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/Plakatraster_Sonderausstellungen_22_1_-1085x1536.jpg 1085w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/Plakatraster_Sonderausstellungen_22_1_.jpg 1356w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eaf5fb5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eaf5fb5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1be8c13\" data-id=\"1be8c13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d0c2cd elementor-widget elementor-widget-text-editor\" data-id=\"9d0c2cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Was ist das Besondere an der Sonderausstellung?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-4a8d318\" data-id=\"4a8d318\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-742f348 elementor-widget elementor-widget-text-editor\" data-id=\"742f348\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir als Forschungsmuseum wollen Forschung an die \u00d6ffentlichkeit bringen und partizipativ mit der \u00d6ffentlichkeit in Diskurs treten. Und so ist auch diese Ausstellung letztlich eine Ausstellung, die den Besucher in die Ermittlungsarbeit der Arch\u00e4olog:innen mitnimmt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11b02c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11b02c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4eb1ba4\" data-id=\"4eb1ba4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce16cb2 elementor-widget elementor-widget-text-editor\" data-id=\"ce16cb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Warum sollten die Menschen Ihrer Meinung nach die neue Sonderausstellung besuchen?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-42b2858\" data-id=\"42b2858\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1119273 elementor-widget elementor-widget-text-editor\" data-id=\"1119273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich glaube, die Besucher:innen bekommen das Faszinosum \u201eArch\u00e4ologie\u201c in einer sehr anschaulichen Weise an einigen ausgew\u00e4hlten Lebensschicksalen der Bergleute, die da verungl\u00fcckt sind, aufgezeigt. Daraus erschlie\u00dft sich eine Lebenswelt, die wir uns heute nicht mehr vorstellen k\u00f6nnen. In unserer westlichen Welt ist die harte k\u00f6rperliche Arbeit nicht mehr das \u00dcbliche. Aber ich glaube, es ist sehr spannend zu sehen, dass Lebensschicksale und Arbeit eng zusammen gehen und sehr unmittelbar sein k\u00f6nnen. Und durch die Verungl\u00fcckung wird das schlagartig bewusst. Wir sind das in unseren B\u00fcrojobs nicht mehr gewohnt, einen Herzinfarkt vielleicht oder mal einen Schlaganfall kennen wir. Aber dass man auch bei der physischen Arbeit verungl\u00fccken kann, das ist in Zentraleuropa nicht h\u00e4ufig. Ich finde es spannend, und ich glaube unsere Ausstellung ist in dieser Richtung sehr anschaulich aufgebaut, so dass die Besucher:innen an dieser Reise in die Lebenswelt der altpersischen Bergleute wirklich viel Vergn\u00fcgen haben werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7e5ca4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7e5ca4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4e8a7cf\" data-id=\"4e8a7cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b3b8be elementor-widget elementor-widget-text-editor\" data-id=\"6b3b8be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Da stimme ich Ihnen zu.\u00a0 Haben Sie noch ein paar abschlie\u00dfende Worte?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-08f0125\" data-id=\"08f0125\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-689eba1 elementor-widget elementor-widget-text-editor\" data-id=\"689eba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Man geht ja immer seinen Weg weiter, und das sage ich auch immer meinen j\u00fcngeren Kolleg:innen: \u201eTrauts euch was und machts was\u201c \u2013 auf gut \u00d6sterreichisch. Dann passiert auch etwas und es geht voran. Wir brauchen in unserer Gesellschaft den Mut, Dinge umzusetzen, und ich glaube, das m\u00fcssen wir immer wieder versuchen. Dann kommt unsere Gesellschaft voran.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0613eea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0613eea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1f8b664\" data-id=\"1f8b664\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53910a9 elementor-widget elementor-widget-text-editor\" data-id=\"53910a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Dann sage ich abschlie\u00dfend: herzlichen Dank, f\u00fcr das Gespr\u00e4ch.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-adc133c\" data-id=\"adc133c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab6c02a elementor-widget elementor-widget-text-editor\" data-id=\"ab6c02a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bitte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb6f5a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb6f5a5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-febca86\" data-id=\"febca86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c32d4b elementor-widget elementor-widget-image\" data-id=\"9c32d4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/DSC20040-1024x683.jpg\" class=\"attachment-large size-large wp-image-54\" alt=\"\" srcset=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/DSC20040-1024x683.jpg 1024w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/DSC20040-300x200.jpg 300w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/DSC20040-768x512.jpg 768w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/DSC20040-1536x1024.jpg 1536w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/DSC20040-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-408df2dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"408df2dd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1533895f\" data-id=\"1533895f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f170e7 elementor-widget elementor-widget-text-editor\" data-id=\"3f170e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Das Interview f\u00fchrte Pia Weber.<\/em><\/p><p><em>Prof. Dr. Thomas St\u00f6llner ist Professor f\u00fcr Ur- und Fr\u00fchgeschichte an der Ruhr-Universit\u00e4t Bochum sowie stellvertretender Museumsdirektor und Forschungsdirektor des Deutschen Bergbau-Museums Bochum, Leibniz-Forschungsmuseum f\u00fcr Georessourcen. Mit der Ur- und Fr\u00fchgeschichte verbindet er\u00a0<\/em><em>viele Rohstofffragen. Das f\u00fchrte ihn schon fr\u00fch an den Bergbau heran. Sein Spezialgebiet ist die Montanarch\u00e4ologie. Er forscht weltweit in diesem Bereich.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8105b0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8105b0a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c3f4787\" data-id=\"c3f4787\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-399a152 elementor-widget elementor-widget-spacer\" data-id=\"399a152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae53e7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae53e7d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3554463\" data-id=\"3554463\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe39b4c elementor-widget elementor-widget-spacer\" data-id=\"fe39b4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a38c16 elementor-author-box--avatar-yes elementor-author-box--name-yes elementor-author-box--biography-yes elementor-author-box--link-no elementor-widget elementor-widget-author-box\" data-id=\"7a38c16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"author-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-author-box\">\n\t\t\t\t\t\t\t<div  class=\"elementor-author-box__avatar\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2023\/03\/cropped-15C21EA0-B159-4A1C-970A-74B06A107D9D-scaled-1-300x300.jpg\" alt=\"Bild von Pia Patrizia Weber\" loading=\"lazy\">\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-author-box__text\">\n\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t<h4 class=\"elementor-author-box__name\">\n\t\t\t\t\t\t\tPia Patrizia Weber\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-author-box__bio\">\n\t\t\t\t\t\tPia ist wissenschaftliche Mitarbeiterin am Deutschen Bergbau-Museum Bochum.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-caff4c9\" data-id=\"caff4c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4e9fa8 elementor-widget elementor-widget-spacer\" data-id=\"f4e9fa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-780c8a8 elementor-widget elementor-widget-heading\" data-id=\"780c8a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Das k\u00f6nnte Dir auch gefallen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d703094 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"d703094\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2867 post type-post status-publish format-standard has-post-thumbnail hentry category-unterfreunden category-unteruns\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/unterirdis.ch\/wordpress\/2026\/03\/30\/folge-58-neues-denkmalgesetz-die-zukunft-des-lwl-entdecken\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2026\/03\/csm_Sandra-Peternek_93af03e201-2-240x300.jpg\" class=\"attachment-medium size-medium wp-image-2854\" alt=\"\" srcset=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2026\/03\/csm_Sandra-Peternek_93af03e201-2-240x300.jpg 240w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2026\/03\/csm_Sandra-Peternek_93af03e201-2-768x960.jpg 768w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2026\/03\/csm_Sandra-Peternek_93af03e201-2.jpg 780w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/unterirdis.ch\/wordpress\/2026\/03\/30\/folge-58-neues-denkmalgesetz-die-zukunft-des-lwl-entdecken\/\" >\n\t\t\t\tFolge 58 -Neues Denkmalgesetz &amp; die Zukunft des LWL entdecken\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30. M\u00e4rz 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/unterirdis.ch\/wordpress\/2026\/03\/30\/folge-58-neues-denkmalgesetz-die-zukunft-des-lwl-entdecken\/\" aria-label=\"Mehr \u00fcber Folge 58 -Neues Denkmalgesetz &amp; die Zukunft des LWL entdecken\" tabindex=\"-1\" >\n\t\t\tWeiterlesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2830 post type-post status-publish format-standard has-post-thumbnail hentry category-im-museum category-an-der-ruhr-universitaet-bochum category-oesterreich tag-deutsches-bergbau-museum-bochum tag-duerrnberg tag-forschung tag-forschungskoordinator tag-podcast tag-ruhr-universitaet-bochum tag-wisskomm\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/12\/19\/folge-56-forschungskoordinator-duerrnberg\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"186\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2025\/12\/csm_20251203_Kooperationsvertrag_Duerrnberg__c_Keltenmuseum_Claudia_Schwenk_19ecbd9ed0-300x186.jpg\" class=\"attachment-medium size-medium wp-image-2831\" alt=\"Die Vertragspartner mit den Unterschriebenen Vertr\u00e4gen der Forschungskooperation.\" srcset=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2025\/12\/csm_20251203_Kooperationsvertrag_Duerrnberg__c_Keltenmuseum_Claudia_Schwenk_19ecbd9ed0-300x186.jpg 300w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2025\/12\/csm_20251203_Kooperationsvertrag_Duerrnberg__c_Keltenmuseum_Claudia_Schwenk_19ecbd9ed0-768x477.jpg 768w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2025\/12\/csm_20251203_Kooperationsvertrag_Duerrnberg__c_Keltenmuseum_Claudia_Schwenk_19ecbd9ed0.jpg 934w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/12\/19\/folge-56-forschungskoordinator-duerrnberg\/\" >\n\t\t\t\tFolge 56 &#8211; Forschungskoordinator D\u00fcrrnberg\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t19. Dezember 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/12\/19\/folge-56-forschungskoordinator-duerrnberg\/\" aria-label=\"Mehr \u00fcber Folge 56 &#8211; Forschungskoordinator D\u00fcrrnberg\" tabindex=\"-1\" >\n\t\t\tWeiterlesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2781 post type-post status-publish format-standard has-post-thumbnail hentry category-im-museum category-an-der-ruhr-universitaet-bochum category-unterfreunden category-unteruns tag-abschied tag-deutsches-bergbau-museum-bochum tag-podcast tag-ruhr-universitaet-bochum tag-wisskomm\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/08\/29\/folge-55-zwei-abschiede\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"82\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/12\/Header-Bsky-nummer-3-300x82.jpg\" class=\"attachment-medium size-medium wp-image-2613\" alt=\"\" srcset=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/12\/Header-Bsky-nummer-3-300x82.jpg 300w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/12\/Header-Bsky-nummer-3-1024x280.jpg 1024w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/12\/Header-Bsky-nummer-3-768x210.jpg 768w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/12\/Header-Bsky-nummer-3.jpg 1235w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/08\/29\/folge-55-zwei-abschiede\/\" >\n\t\t\t\tFolge 55 &#8211; Zwei Abschiede\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t29. August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/08\/29\/folge-55-zwei-abschiede\/\" aria-label=\"Mehr \u00fcber Folge 55 &#8211; Zwei Abschiede\" tabindex=\"-1\" >\n\t\t\tWeiterlesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7154ec1 elementor-widget elementor-widget-spacer\" data-id=\"7154ec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Prof. Dr. Thomas St\u00f6llner gibt&nbsp; uns exklusive Einblicke in seine Arbeit als Arch\u00e4ologe.<\/p>\n","protected":false},"author":2,"featured_media":52,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,10,8,6],"tags":[],"class_list":["post-55","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-im-museum","category-iran","category-oesterreich","category-unterwegs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026 - unterIrdisch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026 - unterIrdisch\" \/>\n<meta property=\"og:description\" content=\"Prof. Dr. Thomas St\u00f6llner gibt&nbsp; uns exklusive Einblicke in seine Arbeit als Arch\u00e4ologe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/\" \/>\n<meta property=\"og:site_name\" content=\"unterIrdisch\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-09T07:35:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T16:25:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pia Patrizia Weber\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unterirdis_ch\" \/>\n<meta name=\"twitter:site\" content=\"@unterirdis_ch\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pia Patrizia Weber\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/\"},\"author\":{\"name\":\"Pia Patrizia Weber\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#\\\/schema\\\/person\\\/e51321391df8a8104f4f9e7ea953fd72\"},\"headline\":\"Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026\",\"datePublished\":\"2020-11-09T07:35:14+00:00\",\"dateModified\":\"2022-07-26T16:25:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/\"},\"wordCount\":1696,\"publisher\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/100jaehriger_Stollen-scaled.jpg\",\"articleSection\":[\"am Deutschen Bergbau-Museum Bochum\",\"Iran\",\"\u00d6sterreich\",\"unterWegs\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/\",\"name\":\"Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026 - unterIrdisch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/100jaehriger_Stollen-scaled.jpg\",\"datePublished\":\"2020-11-09T07:35:14+00:00\",\"dateModified\":\"2022-07-26T16:25:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/100jaehriger_Stollen-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/100jaehriger_Stollen-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"100j\u00e4hriger Stollen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2020\\\/11\\\/09\\\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/\",\"name\":\"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien\",\"description\":\"der Science-Blog aus dem Haus der Arch\u00e4ologien\",\"publisher\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#organization\"},\"alternateName\":\"unterIrdisch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#organization\",\"name\":\"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien\",\"alternateName\":\"unterIrdisch\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo_3000p-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo_3000p-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien\"},\"image\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/unterirdis_ch\",\"https:\\\/\\\/instagram.com\\\/unterirdis.ch\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWj0o58Zp9pOrkbG3Xh2C4Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#\\\/schema\\\/person\\\/e51321391df8a8104f4f9e7ea953fd72\",\"name\":\"Pia Patrizia Weber\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-15C21EA0-B159-4A1C-970A-74B06A107D9D-scaled-1-96x96.jpg\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-15C21EA0-B159-4A1C-970A-74B06A107D9D-scaled-1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-15C21EA0-B159-4A1C-970A-74B06A107D9D-scaled-1-96x96.jpg\",\"caption\":\"Pia Patrizia Weber\"},\"description\":\"Pia ist wissenschaftliche Mitarbeiterin am Deutschen Bergbau-Museum Bochum.\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/author\\\/pweber\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026 - unterIrdisch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/","og_locale":"de_DE","og_type":"article","og_title":"Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026 - unterIrdisch","og_description":"Prof. Dr. Thomas St\u00f6llner gibt&nbsp; uns exklusive Einblicke in seine Arbeit als Arch\u00e4ologe.","og_url":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/","og_site_name":"unterIrdisch","article_published_time":"2020-11-09T07:35:14+00:00","article_modified_time":"2022-07-26T16:25:44+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-scaled.jpg","type":"image\/jpeg"}],"author":"Pia Patrizia Weber","twitter_card":"summary_large_image","twitter_creator":"@unterirdis_ch","twitter_site":"@unterirdis_ch","twitter_misc":{"Verfasst von":"Pia Patrizia Weber","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/#article","isPartOf":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/"},"author":{"name":"Pia Patrizia Weber","@id":"https:\/\/unterirdis.ch\/wordpress\/#\/schema\/person\/e51321391df8a8104f4f9e7ea953fd72"},"headline":"Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026","datePublished":"2020-11-09T07:35:14+00:00","dateModified":"2022-07-26T16:25:44+00:00","mainEntityOfPage":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/"},"wordCount":1696,"publisher":{"@id":"https:\/\/unterirdis.ch\/wordpress\/#organization"},"image":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/#primaryimage"},"thumbnailUrl":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-scaled.jpg","articleSection":["am Deutschen Bergbau-Museum Bochum","Iran","\u00d6sterreich","unterWegs"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/","url":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/","name":"Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026 - unterIrdisch","isPartOf":{"@id":"https:\/\/unterirdis.ch\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/#primaryimage"},"image":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/#primaryimage"},"thumbnailUrl":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-scaled.jpg","datePublished":"2020-11-09T07:35:14+00:00","dateModified":"2022-07-26T16:25:44+00:00","breadcrumb":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/#primaryimage","url":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-scaled.jpg","contentUrl":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2020\/11\/100jaehriger_Stollen-scaled.jpg","width":2560,"height":1920,"caption":"100j\u00e4hriger Stollen"},{"@type":"BreadcrumbList","@id":"https:\/\/unterirdis.ch\/wordpress\/2020\/11\/09\/da-muss-man-weiter-und-heraus-finden-wohin-der-stollen-fuehrt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/unterirdis.ch\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Da muss man weiter und heraus finden, wohin der Stollen f\u00fchrt\u2026"}]},{"@type":"WebSite","@id":"https:\/\/unterirdis.ch\/wordpress\/#website","url":"https:\/\/unterirdis.ch\/wordpress\/","name":"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien","description":"der Science-Blog aus dem Haus der Arch\u00e4ologien","publisher":{"@id":"https:\/\/unterirdis.ch\/wordpress\/#organization"},"alternateName":"unterIrdisch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unterirdis.ch\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/unterirdis.ch\/wordpress\/#organization","name":"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien","alternateName":"unterIrdisch","url":"https:\/\/unterirdis.ch\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/unterirdis.ch\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2022\/03\/logo_3000p-scaled.jpg","contentUrl":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2022\/03\/logo_3000p-scaled.jpg","width":2560,"height":2560,"caption":"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien"},"image":{"@id":"https:\/\/unterirdis.ch\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/unterirdis_ch","https:\/\/instagram.com\/unterirdis.ch","https:\/\/www.youtube.com\/channel\/UCWj0o58Zp9pOrkbG3Xh2C4Q"]},{"@type":"Person","@id":"https:\/\/unterirdis.ch\/wordpress\/#\/schema\/person\/e51321391df8a8104f4f9e7ea953fd72","name":"Pia Patrizia Weber","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2023\/03\/cropped-15C21EA0-B159-4A1C-970A-74B06A107D9D-scaled-1-96x96.jpg","url":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2023\/03\/cropped-15C21EA0-B159-4A1C-970A-74B06A107D9D-scaled-1-96x96.jpg","contentUrl":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2023\/03\/cropped-15C21EA0-B159-4A1C-970A-74B06A107D9D-scaled-1-96x96.jpg","caption":"Pia Patrizia Weber"},"description":"Pia ist wissenschaftliche Mitarbeiterin am Deutschen Bergbau-Museum Bochum.","url":"https:\/\/unterirdis.ch\/wordpress\/author\/pweber\/"}]}},"_links":{"self":[{"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/posts\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/comments?post=55"}],"version-history":[{"count":0,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/posts\/55\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/media\/52"}],"wp:attachment":[{"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/media?parent=55"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/categories?post=55"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/tags?post=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}