{"id":138,"date":"2021-10-20T14:23:47","date_gmt":"2021-10-20T12:23:47","guid":{"rendered":"https:\/\/unterirdis.ch\/wordpress\/?p=138"},"modified":"2022-07-26T18:22:30","modified_gmt":"2022-07-26T16:22:30","slug":"folge-18-unteruns-tod-und-jenseitsvorstellungen","status":"publish","type":"post","link":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/","title":{"rendered":"Folge 18 &#8211; unterUns Tod und Jenseitsvorstellungen im antiken Griechenland"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"138\" class=\"elementor elementor-138\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73d70724 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73d70724\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ee98fa9\" data-id=\"7ee98fa9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db6ee5a elementor-widget elementor-widget-spacer\" data-id=\"db6ee5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd7bbd4 elementor-widget elementor-widget-text-editor\" data-id=\"dd7bbd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Waren unsere vergangenen Folgen doch meist heiter, so widmen wir uns diesmal einem ernsteren Thema. Dem Umgang mit dem Tod in der griechischen Antike und den Jenseitsvorstellungen. Hierzu forscht bei uns in Bochum seit einigen Jahren Dr. Soi Agelidis und bei einem Vornamen der \u201eLeben\u201c bedeutet stellt sich unweigerlich die Frage, warum ausgerechnet mit dem Tod besch\u00e4ftigen?<\/p><p>Nachdem das gekl\u00e4rt ist, geht es einmal reihum, wie ist das Verh\u00e4ltnis der Lebenden zu den Toten? Wieso ist es wichtig, dass die Bestattung korrekt durchgef\u00fchrt wird und wieso steht Patroklos vor den Toren der Unterwelt und darf nicht rein?<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-338405d8 elementor-widget elementor-widget-text-editor\" data-id=\"338405d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\r\n<p style=\"text-align: center;\"><iframe src=\"https:\/\/www.podcaster.de\/simpleplayer\/?id=show~e2k8ju~unterirdisch~pod-23070471a7ab37e073b05547a3&amp;v=1634735115\" width=\"100%\" height=\"\" style=\"width: 100%; min-width: 275px; min-height: 300px; max-width: 475px; max-height: 300px; border: 0; overflow: hidden;\" frameborder=\"0\"><\/iframe><\/p>\r\n<p>Wir alle kennen Hades als den Gott der Unterwelt, in Disneys Herkules als b\u00f6se und grausam dargestellt, aber stimmt das \u00fcberhaupt? \u00dcberraschend ist auch, dass trotz der enormen Wichtigkeit des Gottes der Unterwelt nur wenige Kultpl\u00e4tze existieren, anders als bei anderen G\u00f6ttern. Aber auch hierf\u00fcr hat Soi eine Erkl\u00e4rung. Und wie k\u00f6nnte es bei uns Bochumern anders sein, auch der Bergbau wird kurz angeschnitten, aber warum? &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\r\n<p><span style=\"font-family: var(--bs-body-font-family); font-size: var(--bs-body-font-size); font-weight: var(--bs-body-font-weight); text-align: var(--bs-body-text-align); caret-color: auto;\">Schreibt uns eure Meinung gerne in die Kommentare oder bei <\/span><a href=\"https:\/\/twitter.com\/unterirdis_ch\" target=\"_blank\" rel=\"noopener\" style=\"font-family: var(--bs-body-font-family); font-size: var(--bs-body-font-size); font-weight: var(--bs-body-font-weight); text-align: var(--bs-body-text-align);\">Twitter (@unterirdis_ch)<\/a><span style=\"font-family: var(--bs-body-font-family); font-size: var(--bs-body-font-size); font-weight: var(--bs-body-font-weight); text-align: var(--bs-body-text-align); caret-color: auto;\">&nbsp;und&nbsp;<\/span><a href=\"https:\/\/www.instagram.com\/unterirdis.ch\/\" target=\"_blank\" rel=\"noopener\" style=\"font-family: var(--bs-body-font-family); font-size: var(--bs-body-font-size); font-weight: var(--bs-body-font-weight); text-align: var(--bs-body-text-align);\">Instagram (@unterirdis.ch)<\/a><span style=\"font-family: var(--bs-body-font-family); font-size: var(--bs-body-font-size); font-weight: var(--bs-body-font-weight); text-align: var(--bs-body-text-align); caret-color: auto;\">!<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b244829 elementor-widget elementor-widget-spacer\" data-id=\"b244829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a743c2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a743c2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3e604fe\" data-id=\"3e604fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c64b112 elementor-widget elementor-widget-spacer\" data-id=\"c64b112\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-202467b elementor-author-box--avatar-yes elementor-author-box--name-yes elementor-author-box--biography-yes elementor-author-box--link-no elementor-widget elementor-widget-author-box\" data-id=\"202467b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"author-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-author-box\">\n\t\t\t\t\t\t\t<div  class=\"elementor-author-box__avatar\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/07\/cropped-P1320573-e1755606392802-300x300.jpg\" alt=\"Bild von Dominic Bachmann\" loading=\"lazy\">\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-author-box__text\">\n\t\t\t\t\t\t\t\t\t<div >\n\t\t\t\t\t\t<h4 class=\"elementor-author-box__name\">\n\t\t\t\t\t\t\tDominic Bachmann\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-author-box__bio\">\n\t\t\t\t\t\tDominic war wissenschaftlicher Mitarbeiter an der Ruhr-Universit\u00e4t Bochum.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f0972e2\" data-id=\"f0972e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aecc54f elementor-widget elementor-widget-spacer\" data-id=\"aecc54f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59c8340 elementor-widget elementor-widget-heading\" data-id=\"59c8340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Das k\u00f6nnte Dir auch gefallen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e9d10d elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-widget elementor-widget-posts\" data-id=\"9e9d10d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;3&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2867 post type-post status-publish format-standard has-post-thumbnail hentry category-unterfreunden category-unteruns\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/unterirdis.ch\/wordpress\/2026\/03\/30\/folge-58-neues-denkmalgesetz-die-zukunft-des-lwl-entdecken\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2026\/03\/csm_Sandra-Peternek_93af03e201-2-240x300.jpg\" class=\"attachment-medium size-medium wp-image-2854\" alt=\"\" srcset=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2026\/03\/csm_Sandra-Peternek_93af03e201-2-240x300.jpg 240w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2026\/03\/csm_Sandra-Peternek_93af03e201-2-768x960.jpg 768w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2026\/03\/csm_Sandra-Peternek_93af03e201-2.jpg 780w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/unterirdis.ch\/wordpress\/2026\/03\/30\/folge-58-neues-denkmalgesetz-die-zukunft-des-lwl-entdecken\/\" >\n\t\t\t\tFolge 58 -Neues Denkmalgesetz &amp; die Zukunft des LWL entdecken\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30. M\u00e4rz 2026\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/unterirdis.ch\/wordpress\/2026\/03\/30\/folge-58-neues-denkmalgesetz-die-zukunft-des-lwl-entdecken\/\" aria-label=\"Mehr \u00fcber Folge 58 -Neues Denkmalgesetz &amp; die Zukunft des LWL entdecken\" tabindex=\"-1\" >\n\t\t\tWeiterlesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2830 post type-post status-publish format-standard has-post-thumbnail hentry category-im-museum category-an-der-ruhr-universitaet-bochum category-oesterreich tag-deutsches-bergbau-museum-bochum tag-duerrnberg tag-forschung tag-forschungskoordinator tag-podcast tag-ruhr-universitaet-bochum tag-wisskomm\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/12\/19\/folge-56-forschungskoordinator-duerrnberg\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"186\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2025\/12\/csm_20251203_Kooperationsvertrag_Duerrnberg__c_Keltenmuseum_Claudia_Schwenk_19ecbd9ed0-300x186.jpg\" class=\"attachment-medium size-medium wp-image-2831\" alt=\"Die Vertragspartner mit den Unterschriebenen Vertr\u00e4gen der Forschungskooperation.\" srcset=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2025\/12\/csm_20251203_Kooperationsvertrag_Duerrnberg__c_Keltenmuseum_Claudia_Schwenk_19ecbd9ed0-300x186.jpg 300w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2025\/12\/csm_20251203_Kooperationsvertrag_Duerrnberg__c_Keltenmuseum_Claudia_Schwenk_19ecbd9ed0-768x477.jpg 768w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2025\/12\/csm_20251203_Kooperationsvertrag_Duerrnberg__c_Keltenmuseum_Claudia_Schwenk_19ecbd9ed0.jpg 934w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/12\/19\/folge-56-forschungskoordinator-duerrnberg\/\" >\n\t\t\t\tFolge 56 &#8211; Forschungskoordinator D\u00fcrrnberg\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t19. Dezember 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/12\/19\/folge-56-forschungskoordinator-duerrnberg\/\" aria-label=\"Mehr \u00fcber Folge 56 &#8211; Forschungskoordinator D\u00fcrrnberg\" tabindex=\"-1\" >\n\t\t\tWeiterlesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2781 post type-post status-publish format-standard has-post-thumbnail hentry category-im-museum category-an-der-ruhr-universitaet-bochum category-unterfreunden category-unteruns tag-abschied tag-deutsches-bergbau-museum-bochum tag-podcast tag-ruhr-universitaet-bochum tag-wisskomm\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/08\/29\/folge-55-zwei-abschiede\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"82\" src=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/12\/Header-Bsky-nummer-3-300x82.jpg\" class=\"attachment-medium size-medium wp-image-2613\" alt=\"\" srcset=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/12\/Header-Bsky-nummer-3-300x82.jpg 300w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/12\/Header-Bsky-nummer-3-1024x280.jpg 1024w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/12\/Header-Bsky-nummer-3-768x210.jpg 768w, https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/12\/Header-Bsky-nummer-3.jpg 1235w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/08\/29\/folge-55-zwei-abschiede\/\" >\n\t\t\t\tFolge 55 &#8211; Zwei Abschiede\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t29. August 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/unterirdis.ch\/wordpress\/2025\/08\/29\/folge-55-zwei-abschiede\/\" aria-label=\"Mehr \u00fcber Folge 55 &#8211; Zwei Abschiede\" tabindex=\"-1\" >\n\t\t\tWeiterlesen \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76bb5b6 elementor-widget elementor-widget-spacer\" data-id=\"76bb5b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Waren unsere vergangenen Folgen doch meist heiter, so widmen wir uns diesmal einem ernsteren Thema. Dem Umgang mit dem Tod in der griechischen Antike und den Jenseitsvorstellungen. Hierzu forscht bei uns in Bochum seit einigen Jahren Dr. Soi Agelidis und bei einem Vornamen der \u201eLeben\u201c bedeutet stellt sich unweigerlich die Frage, warum ausgerechnet mit dem Tod besch\u00e4ftigen?<br \/>\nNachdem das gekl\u00e4rt ist, geht es einmal reihum, wie ist das Verh\u00e4ltnis der Lebenden zu den Toten? Wieso ist es wichtig, dass die Bestattung korrekt durchgef\u00fchrt wird und wieso steht Patroklos vor den Toren der Unterwelt und darf nicht rein?<\/p>\n","protected":false},"author":3,"featured_media":693,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87,12],"tags":[],"class_list":["post-138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-griechenland","category-unterfreunden"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Folge 18 - unterUns Tod und Jenseitsvorstellungen im antiken Griechenland - unterIrdisch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Folge 18 - unterUns Tod und Jenseitsvorstellungen im antiken Griechenland - unterIrdisch\" \/>\n<meta property=\"og:description\" content=\"Waren unsere vergangenen Folgen doch meist heiter, so widmen wir uns diesmal einem ernsteren Thema. Dem Umgang mit dem Tod in der griechischen Antike und den Jenseitsvorstellungen. Hierzu forscht bei uns in Bochum seit einigen Jahren Dr. Soi Agelidis und bei einem Vornamen der \u201eLeben\u201c bedeutet stellt sich unweigerlich die Frage, warum ausgerechnet mit dem Tod besch\u00e4ftigen? Nachdem das gekl\u00e4rt ist, geht es einmal reihum, wie ist das Verh\u00e4ltnis der Lebenden zu den Toten? Wieso ist es wichtig, dass die Bestattung korrekt durchgef\u00fchrt wird und wieso steht Patroklos vor den Toren der Unterwelt und darf nicht rein?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/\" \/>\n<meta property=\"og:site_name\" content=\"unterIrdisch\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-20T12:23:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T16:22:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unterirdis.ch\/wp-content\/uploads\/2021\/10\/Griechenland_Tod.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"553\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dominic Bachmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unterirdis_ch\" \/>\n<meta name=\"twitter:site\" content=\"@unterirdis_ch\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dominic Bachmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/\"},\"author\":{\"name\":\"Dominic Bachmann\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#\\\/schema\\\/person\\\/50e7ff29f34fcda3f64338fd095708c9\"},\"headline\":\"Folge 18 &#8211; unterUns Tod und Jenseitsvorstellungen im antiken Griechenland\",\"datePublished\":\"2021-10-20T12:23:47+00:00\",\"dateModified\":\"2022-07-26T16:22:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/\"},\"wordCount\":212,\"publisher\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Griechenland_Tod.jpg\",\"articleSection\":[\"Griechenland\",\"unterFreunden\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/\",\"name\":\"Folge 18 - unterUns Tod und Jenseitsvorstellungen im antiken Griechenland - unterIrdisch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Griechenland_Tod.jpg\",\"datePublished\":\"2021-10-20T12:23:47+00:00\",\"dateModified\":\"2022-07-26T16:22:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Griechenland_Tod.jpg\",\"contentUrl\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Griechenland_Tod.jpg\",\"width\":900,\"height\":553},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/2021\\\/10\\\/20\\\/folge-18-unteruns-tod-und-jenseitsvorstellungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Folge 18 &#8211; unterUns Tod und Jenseitsvorstellungen im antiken Griechenland\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/\",\"name\":\"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien\",\"description\":\"der Science-Blog aus dem Haus der Arch\u00e4ologien\",\"publisher\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#organization\"},\"alternateName\":\"unterIrdisch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#organization\",\"name\":\"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien\",\"alternateName\":\"unterIrdisch\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo_3000p-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/logo_3000p-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien\"},\"image\":{\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/unterirdis_ch\",\"https:\\\/\\\/instagram.com\\\/unterirdis.ch\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWj0o58Zp9pOrkbG3Xh2C4Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/#\\\/schema\\\/person\\\/50e7ff29f34fcda3f64338fd095708c9\",\"name\":\"Dominic Bachmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-P1320573-e1755606392802-96x96.jpg\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-P1320573-e1755606392802-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/unterirdis.ch\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/cropped-P1320573-e1755606392802-96x96.jpg\",\"caption\":\"Dominic Bachmann\"},\"description\":\"Dominic war wissenschaftlicher Mitarbeiter an der Ruhr-Universit\u00e4t Bochum.\",\"url\":\"https:\\\/\\\/unterirdis.ch\\\/wordpress\\\/author\\\/dbachmann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Folge 18 - unterUns Tod und Jenseitsvorstellungen im antiken Griechenland - unterIrdisch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/","og_locale":"de_DE","og_type":"article","og_title":"Folge 18 - unterUns Tod und Jenseitsvorstellungen im antiken Griechenland - unterIrdisch","og_description":"Waren unsere vergangenen Folgen doch meist heiter, so widmen wir uns diesmal einem ernsteren Thema. Dem Umgang mit dem Tod in der griechischen Antike und den Jenseitsvorstellungen. Hierzu forscht bei uns in Bochum seit einigen Jahren Dr. Soi Agelidis und bei einem Vornamen der \u201eLeben\u201c bedeutet stellt sich unweigerlich die Frage, warum ausgerechnet mit dem Tod besch\u00e4ftigen? Nachdem das gekl\u00e4rt ist, geht es einmal reihum, wie ist das Verh\u00e4ltnis der Lebenden zu den Toten? Wieso ist es wichtig, dass die Bestattung korrekt durchgef\u00fchrt wird und wieso steht Patroklos vor den Toren der Unterwelt und darf nicht rein?","og_url":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/","og_site_name":"unterIrdisch","article_published_time":"2021-10-20T12:23:47+00:00","article_modified_time":"2022-07-26T16:22:30+00:00","og_image":[{"width":900,"height":553,"url":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2021\/10\/Griechenland_Tod.jpg","type":"image\/jpeg"}],"author":"Dominic Bachmann","twitter_card":"summary_large_image","twitter_creator":"@unterirdis_ch","twitter_site":"@unterirdis_ch","twitter_misc":{"Verfasst von":"Dominic Bachmann","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/#article","isPartOf":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/"},"author":{"name":"Dominic Bachmann","@id":"https:\/\/unterirdis.ch\/wordpress\/#\/schema\/person\/50e7ff29f34fcda3f64338fd095708c9"},"headline":"Folge 18 &#8211; unterUns Tod und Jenseitsvorstellungen im antiken Griechenland","datePublished":"2021-10-20T12:23:47+00:00","dateModified":"2022-07-26T16:22:30+00:00","mainEntityOfPage":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/"},"wordCount":212,"publisher":{"@id":"https:\/\/unterirdis.ch\/wordpress\/#organization"},"image":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/#primaryimage"},"thumbnailUrl":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2021\/10\/Griechenland_Tod.jpg","articleSection":["Griechenland","unterFreunden"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/","url":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/","name":"Folge 18 - unterUns Tod und Jenseitsvorstellungen im antiken Griechenland - unterIrdisch","isPartOf":{"@id":"https:\/\/unterirdis.ch\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/#primaryimage"},"image":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/#primaryimage"},"thumbnailUrl":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2021\/10\/Griechenland_Tod.jpg","datePublished":"2021-10-20T12:23:47+00:00","dateModified":"2022-07-26T16:22:30+00:00","breadcrumb":{"@id":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/#primaryimage","url":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2021\/10\/Griechenland_Tod.jpg","contentUrl":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2021\/10\/Griechenland_Tod.jpg","width":900,"height":553},{"@type":"BreadcrumbList","@id":"https:\/\/unterirdis.ch\/wordpress\/2021\/10\/20\/folge-18-unteruns-tod-und-jenseitsvorstellungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/unterirdis.ch\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Folge 18 &#8211; unterUns Tod und Jenseitsvorstellungen im antiken Griechenland"}]},{"@type":"WebSite","@id":"https:\/\/unterirdis.ch\/wordpress\/#website","url":"https:\/\/unterirdis.ch\/wordpress\/","name":"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien","description":"der Science-Blog aus dem Haus der Arch\u00e4ologien","publisher":{"@id":"https:\/\/unterirdis.ch\/wordpress\/#organization"},"alternateName":"unterIrdisch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unterirdis.ch\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/unterirdis.ch\/wordpress\/#organization","name":"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien","alternateName":"unterIrdisch","url":"https:\/\/unterirdis.ch\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/unterirdis.ch\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2022\/03\/logo_3000p-scaled.jpg","contentUrl":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2022\/03\/logo_3000p-scaled.jpg","width":2560,"height":2560,"caption":"unterIrdisch - der Science-Blog aus dem Haus der Arch\u00e4ologien"},"image":{"@id":"https:\/\/unterirdis.ch\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/unterirdis_ch","https:\/\/instagram.com\/unterirdis.ch","https:\/\/www.youtube.com\/channel\/UCWj0o58Zp9pOrkbG3Xh2C4Q"]},{"@type":"Person","@id":"https:\/\/unterirdis.ch\/wordpress\/#\/schema\/person\/50e7ff29f34fcda3f64338fd095708c9","name":"Dominic Bachmann","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/07\/cropped-P1320573-e1755606392802-96x96.jpg","url":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/07\/cropped-P1320573-e1755606392802-96x96.jpg","contentUrl":"https:\/\/unterirdis.ch\/wp-content\/uploads\/2024\/07\/cropped-P1320573-e1755606392802-96x96.jpg","caption":"Dominic Bachmann"},"description":"Dominic war wissenschaftlicher Mitarbeiter an der Ruhr-Universit\u00e4t Bochum.","url":"https:\/\/unterirdis.ch\/wordpress\/author\/dbachmann\/"}]}},"_links":{"self":[{"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/posts\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/comments?post=138"}],"version-history":[{"count":0,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/posts\/138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/media\/693"}],"wp:attachment":[{"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/media?parent=138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/categories?post=138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/unterirdis.ch\/wordpress\/wp-json\/wp\/v2\/tags?post=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}